{"id":3312,"date":"2021-11-08T10:43:14","date_gmt":"2021-11-08T09:43:14","guid":{"rendered":"https:\/\/mount-everest-tea.com\/cgv\/"},"modified":"2022-08-18T09:48:33","modified_gmt":"2022-08-18T07:48:33","slug":"cgv","status":"publish","type":"page","link":"https:\/\/mount-everest-tea.com\/fr\/cgv\/","title":{"rendered":"CONDITIONS G\u00c9N\u00c9RALES DE VENTE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css=\u00a0\u00bb.vc_custom_1596616112357{margin-top: 60px !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1660299905405{margin-bottom: 0px !important;}\u00a0\u00bb]\n<h2>CONDITIONS DE VENTE ET DE LIVRAISON DE LA SOCI\u00c9T\u00c9 MOUNT EVEREST TEA COMPANY GMBH<\/h2>\n<p><strong>1) Champ d&rsquo;application des pr\u00e9sentes conditions<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) Les livraisons, prestations et offres du vendeur s&rsquo;adressent exclusivement aux entrepreneurs au sens du \u00a7 14 du Code civil allemand (BGB) et sont effectu\u00e9es exclusivement sur la base des pr\u00e9sentes conditions de vente et de livraison. Elles s&rsquo;appliquent \u00e0 toutes les conclusions de contrats entre les parties et s&rsquo;\u00e9tendent aux offres, aux conseils et aux autres prestations contractuelles.<\/p>\n<p style=\"padding-left: 40px;\">b) Les d\u00e9rogations aux pr\u00e9sentes conditions de vente et de livraison ne sont valables que si le vendeur les confirme par \u00e9crit. Les conditions g\u00e9n\u00e9rales de vente de l&rsquo;acheteur ne sont pas valables, elles sont par la pr\u00e9sente contredites. Les conditions de vente et de livraison du vendeur s&rsquo;appliquent \u00e9galement lorsque le vendeur accepte sans r\u00e9serve la prestation de l&rsquo;acheteur tout en ayant connaissance de conditions contraires ou diff\u00e9rentes des pr\u00e9sentes conditions de vente et de livraison. Ni l&rsquo;absence de contestation, ni le paiement, ni l&rsquo;acceptation des marchandises ne constituent une reconnaissance des conditions de vente d&rsquo;autrui.<\/p>\n<p style=\"padding-left: 40px;\">c) s&rsquo;il existe un accord-cadre entre l&rsquo;acheteur et le vendeur, les pr\u00e9sentes conditions de vente et de livraison s&rsquo;appliquent tant \u00e0 l&rsquo;accord-cadre qu&rsquo;aux diff\u00e9rents contrats de vente.<\/p>\n<p style=\"padding-left: 40px;\">d) En passant sa commande, l&rsquo;acheteur d\u00e9clare de mani\u00e8re contraignante qu&rsquo;il est entrepreneur au sens de l&rsquo;article 14 du Code civil allemand (BGB). Les commandes de consommateurs au sens de l&rsquo;article 13 du Code civil allemand (BGB) ne sont pas accept\u00e9es ni ex\u00e9cut\u00e9es.<\/p>\n<p><strong><br \/>\n2. conclusion du contrat, modifications du contrat et forme \u00e9crite<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) Toutes les offres du vendeur sont sans engagement et non contractuelles jusqu&rsquo;\u00e0 la conclusion du contrat et sont soumises \u00e0 la r\u00e9serve de vente interm\u00e9diaire, sauf convention contraire expresse.<\/p>\n<p style=\"padding-left: 40px;\">b) Le contrat est conclu lorsque le vendeur confirme par \u00e9crit ou ex\u00e9cute la commande de l&rsquo;acheteur dans les deux semaines suivant sa r\u00e9ception. En l&rsquo;absence d&rsquo;une autre confirmation \u00e9crite de la part du vendeur, sa facture vaut confirmation de la commande, \u00e0 moins que la livraison elle-m\u00eame n&rsquo;ait d\u00e9j\u00e0 \u00e9t\u00e9 effectu\u00e9e.<\/p>\n<p style=\"padding-left: 40px;\">c) pour les commandes \u00e9crites, le vendeur se base sur le num\u00e9ro d&rsquo;article et non sur la description. Si l&rsquo;acheteur est un commer\u00e7ant, seule la confirmation \u00e9crite du vendeur fait foi pour le contenu des commandes et des accords, sauf si l&rsquo;acheteur s&rsquo;y oppose imm\u00e9diatement par \u00e9crit. Cela vaut en particulier pour les commandes et les accords oraux ou t\u00e9l\u00e9phoniques. En tout \u00e9tat de cause, une notification au vendeur n&rsquo;est plus imm\u00e9diate si elle n&rsquo;est pas parvenue au vendeur dans les deux jours suivant la r\u00e9ception par l&rsquo;acheteur de la confirmation \u00e9crite du vendeur.<\/p>\n<p style=\"padding-left: 40px;\">d) les \u00e9ventuelles modifications ou compl\u00e9ments du contrat, \u00e0 l&rsquo;exception d&rsquo;une modification des conditions de vente et de livraison pour l&rsquo;avenir, apr\u00e8s notification \u00e0 l&rsquo;acheteur conform\u00e9ment au point 1, n\u00e9cessitent la confirmation \u00e9crite du vendeur pour \u00eatre valables. Cela vaut \u00e9galement pour les d\u00e9rogations aux exigences contractuelles de forme \u00e9crite.<\/p>\n<p><strong>3. livraison et d\u00e9lais de livraison<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) Sauf convention contraire expresse et \u00e9crite entre les parties, l&rsquo;exp\u00e9dition des marchandises s&rsquo;effectue EXW (ex works, Incoterms 2010) \u00e0 partir de l&rsquo;entrep\u00f4t d&rsquo;Elmshorn.<\/p>\n<p style=\"padding-left: 40px;\">b) Sous r\u00e9serve d&rsquo;approvisionnement correct et en temps voulu par nos propres fournisseurs, si l&rsquo;acheteur est un commer\u00e7ant.<\/p>\n<p style=\"padding-left: 40px;\">c) En l&rsquo;absence d&rsquo;instructions particuli\u00e8res de l&rsquo;acheteur, le choix de l&rsquo;itin\u00e9raire de transport est effectu\u00e9 par le vendeur selon sa meilleure appr\u00e9ciation, sans responsabilit\u00e9 pour le transport le moins cher et\/ou le plus s\u00fbr.<\/p>\n<p style=\"padding-left: 40px;\">d) Tous les accords et promesses de dates ou de d\u00e9lais de livraison n\u00e9cessitent la forme \u00e9crite pour \u00eatre valables. Le respect des d\u00e9lais de livraison convenus est subordonn\u00e9 \u00e0 l&rsquo;ex\u00e9cution en temps voulu des obligations contractuelles assum\u00e9es par l&rsquo;acheteur, notamment la prestation au paiement convenu et, le cas \u00e9ch\u00e9ant, la fourniture des garanties convenues.<\/p>\n<p style=\"padding-left: 40px;\">e) En cas de retard de livraison, l&rsquo;acheteur n&rsquo;est autoris\u00e9 \u00e0 faire valoir des droits \u00e0 dommages et int\u00e9r\u00eats que si le d\u00e9lai suppl\u00e9mentaire raisonnable qu&rsquo;il a accord\u00e9 par \u00e9crit pour la livraison apr\u00e8s le d\u00e9but du retard s&rsquo;est \u00e9coul\u00e9 sans r\u00e9sultat et si le retard de livraison est imputable au vendeur.<\/p>\n<p style=\"padding-left: 40px;\">f) Les marchandises annonc\u00e9es comme \u00e9tant pr\u00eates \u00e0 \u00eatre exp\u00e9di\u00e9es doivent \u00eatre retir\u00e9es d\u00e8s que la date de livraison est atteinte. Si l&rsquo;exp\u00e9dition est retard\u00e9e en raison de circonstances imputables \u00e0 l&rsquo;acheteur, celui-ci est en retard \u00e0 partir du jour o\u00f9 il est inform\u00e9 que la marchandise est pr\u00eate \u00e0 \u00eatre exp\u00e9di\u00e9e.<\/p>\n<p><strong>4. force majeure<\/strong><\/p>\n<p>En cas de \u00ab\u00a0force majeure\u00a0\u00bb, c&rsquo;est-\u00e0-dire de difficult\u00e9s impr\u00e9vues dues \u00e0 une p\u00e9nurie naturelle de mati\u00e8res premi\u00e8res, \u00e0 des restrictions et \u00e0 des arr\u00eats d&rsquo;exploitation ainsi qu&rsquo;\u00e0 des perturbations impr\u00e9visibles de la production chez le vendeur ou chez ses fournisseurs, \u00e0 des inondations, \u00e0 des temp\u00eates et \u00e0 des intemp\u00e9ries, \u00e0 des ordres et\/ou \u00e0 des contr\u00f4les gouvernementaux et officiels, \u00e0 des entraves totales ou partielles \u00e0 la croissance de la r\u00e9colte, et \u00e0 d&rsquo;autres \u00e9v\u00e9nements non imputables au vendeur, ce dernier est en droit de reporter en cons\u00e9quence la date de livraison annonc\u00e9e ou convenue. Le vendeur est tenu d&rsquo;informer l&rsquo;acheteur de telles circonstances sans d\u00e9lai, d\u00e8s que le vendeur en a connaissance. Si un retard dans l&rsquo;ex\u00e9cution de la prestation en raison d&rsquo;un \u00ab\u00a0cas de force majeure\u00a0\u00bb est inacceptable pour une partie, cette partie est en droit de r\u00e9silier le contrat.<\/p>\n<p><strong>5. l&rsquo;assurance transport, les suppl\u00e9ments de p\u00e9age et de diesel<\/strong><\/p>\n<p>L&rsquo;acheteur est libre de souscrire une assurance transport suppl\u00e9mentaire. Dans ce cas, le vendeur facture en plus 1% du prix d&rsquo;achat net de tous les articles comme frais d&rsquo;assurance. Si aucune assurance transport n&rsquo;est souhait\u00e9e, le vendeur livre exclusivement aux risques de l&rsquo;acheteur (il n&rsquo;y a pas de droit de r\u00e9clamation en cas de dommage pendant le transport). Les p\u00e9ages actuels sont indiqu\u00e9s s\u00e9par\u00e9ment par le vendeur.<br \/>\n<strong><br \/>\n6. premi\u00e8res livraisons<\/strong><\/p>\n<p>Les premi\u00e8res livraisons ne sont effectu\u00e9es que contre remboursement ou paiement anticip\u00e9.<\/p>\n<p><strong>7. prix, co\u00fbts et valeur minimale de la commande<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) Le prix s&rsquo;entend EXW (ex works, Incoterms 2010) \u00e0 partir du si\u00e8ge du vendeur ou directement \u00e0 partir de l&rsquo;entrep\u00f4t de livraison d&rsquo;Elmshorn ou du si\u00e8ge du fournisseur en amont et plus la taxe sur le chiffre d&rsquo;affaires \u00e9ventuellement due, sauf convention contraire \u00e9crite au cas par cas. Ne sont pas compris dans le prix les frais de port, les p\u00e9ages, les surcharges de diesel et autres taxes et redevances de tiers publics ou priv\u00e9s. Il en va de m\u00eame pour les frais de transport, \u00e0 moins qu&rsquo;il n&rsquo;en soit express\u00e9ment convenu autrement. Frais d&rsquo;assurance, ne sont pas inclus dans le prix indiqu\u00e9, voir ch. 5.<\/p>\n<p style=\"padding-left: 40px;\">b) En Suisse, la valeur minimale de la commande est de 150,- \u20ac. Jusqu&rsquo;\u00e0 une valeur de commande de 250 \u20ac, nous indiquons les frais de transport actuels. A partir d&rsquo;une valeur nette de commande de 250,- \u20ac, le vendeur livre franco de port \u00e0 partir de l&rsquo;entrep\u00f4t d&rsquo;Elmshorn. Le montant minimum de la commande pour l&rsquo;\u00e9tranger est de 500,- \u20ac. Le vendeur peut modifier les majorations pour quantit\u00e9 insuffisante et les forfaits mentionn\u00e9s, y compris les augmenter, si ses propres frais de traitement des quantit\u00e9s insuffisantes ou ses propres frais de transport et d&#8217;emballage augmentent. Toutefois, cela ne s&rsquo;applique pas r\u00e9troactivement aux contrats de fourniture d\u00e9j\u00e0 conclus. Sauf accord contraire, le vendeur s&rsquo;en tient aux prix qu&rsquo;il a indiqu\u00e9s pendant 30 jours \u00e0 compter de la date d&rsquo;indication. Les \u00e9ventuelles augmentations de prix dues \u00e0 des mesures administratives apr\u00e8s la conclusion du contrat, caus\u00e9es par des taxes, des droits de douane, des frais de transport, des taux de change ou d&rsquo;autres taxes ou augmentations de quelque nature que ce soit, sont toujours \u00e0 la charge de l&rsquo;acheteur.<\/p>\n<p style=\"padding-left: 40px;\">c) en cas de vente sur appel, le vendeur est li\u00e9 par le prix confirm\u00e9 pendant une p\u00e9riode de trois mois \u00e0 compter de la date de confirmation de la commande. En cas d&rsquo;appel de la marchandise apr\u00e8s l&rsquo;expiration de ce d\u00e9lai, le vendeur est en droit de facturer les prix en vigueur au moment de l&rsquo;appel.<\/p>\n<p><strong>8. reprise des emballages<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) Si le vendeur est tenu, en vertu du d\u00e9cret sur les emballages, de reprendre gratuitement les emballages de transport, de service ou de vente, le lieu de restitution est le si\u00e8ge social du vendeur.<\/p>\n<p style=\"padding-left: 40px;\">b) Le retour des emballages ne peut se faire que pendant les heures d&rsquo;ouverture du vendeur. Les quantit\u00e9s plus importantes doivent \u00eatre annonc\u00e9es au pr\u00e9alable. Les emballages retourn\u00e9s doivent \u00eatre propres et exempts de mati\u00e8res \u00e9trang\u00e8res. Dans le cas contraire, le vendeur est en droit de r\u00e9clamer le remboursement des frais suppl\u00e9mentaires occasionn\u00e9s par l&rsquo;\u00e9limination.<\/p>\n<p><strong>9. r\u00e9serve de propri\u00e9t\u00e9<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) Le vendeur se r\u00e9serve la propri\u00e9t\u00e9 des produits livr\u00e9s jusqu&rsquo;au paiement int\u00e9gral de toutes les cr\u00e9ances r\u00e9sultant de la relation commerciale avec l&rsquo;acheteur.<\/p>\n<p style=\"padding-left: 40px;\">b) Le traitement ou l&rsquo;usinage de la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 par l&rsquo;acheteur est toujours effectu\u00e9 sur ordre du vendeur, sans qu&rsquo;il en r\u00e9sulte des obligations pour ce dernier. La propri\u00e9t\u00e9 des nouveaux biens dans leur \u00e9tat de traitement ou de transformation respectif revient au vendeur. Si la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 du vendeur est transform\u00e9e, trait\u00e9e, m\u00e9lang\u00e9e ou li\u00e9e \u00e0 d&rsquo;autres produits qui ne lui appartiennent pas, il a un droit de copropri\u00e9t\u00e9 sur la nouvelle chose, et ce au prorata du prix factur\u00e9 de la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 par rapport au prix factur\u00e9 des autres produits.<\/p>\n<p style=\"padding-left: 40px;\">c) l&rsquo;acheteur peut vendre la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 exclusive ou de copropri\u00e9t\u00e9 du vendeur dans le cadre de ses activit\u00e9s commerciales normales ; il n&rsquo;est pas autoris\u00e9 \u00e0 la mettre en gage, \u00e0 la c\u00e9der \u00e0 titre de s\u00fbret\u00e9 ou \u00e0 la transf\u00e9rer. L&rsquo;acheteur c\u00e8de d\u00e8s \u00e0 pr\u00e9sent et par avance au vendeur toutes les cr\u00e9ances qui lui reviennent du fait de la revente de la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 ou des produits issus de la transformation, du traitement, du m\u00e9lange, de l&rsquo;incorporation ou de la liaison. Ceci s&rsquo;applique \u00e9galement lorsque les produits sont vendus avec d&rsquo;autres produits n&rsquo;appartenant pas au vendeur pour un prix global. Si, en vertu d&rsquo;une disposition l\u00e9gale, un tiers a acquis des droits de propri\u00e9t\u00e9 ou de copropri\u00e9t\u00e9 sur les produits \u00e0 la suite d&rsquo;un traitement, d&rsquo;une transformation, d&rsquo;un m\u00e9lange ou d&rsquo;une association, l&rsquo;acheteur c\u00e8de \u00e9galement d\u00e8s \u00e0 pr\u00e9sent et par avance au vendeur les droits qu&rsquo;il d\u00e9tient \u00e0 l&rsquo;\u00e9gard du tiers. Les cessions au sens du pr\u00e9sent paragraphe ne s&rsquo;effectuent toujours que jusqu&rsquo;\u00e0 concurrence du prix factur\u00e9 de la marchandise sous r\u00e9serve de propri\u00e9t\u00e9. L&rsquo;acheteur est autoris\u00e9 \u00e0 recouvrer les cr\u00e9ances c\u00e9d\u00e9es jusqu&rsquo;\u00e0 leur r\u00e9vocation, autoris\u00e9e \u00e0 tout moment.<\/p>\n<p>Le vendeur accepte d&rsquo;ores et d\u00e9j\u00e0 les cessions de l&rsquo;acheteur pr\u00e9vues dans ce paragraphe.<\/p>\n<p style=\"padding-left: 40px;\">d) Le vendeur s&rsquo;engage \u00e0 lib\u00e9rer, \u00e0 son choix et \u00e0 la demande de l&rsquo;acheteur, les garanties auxquelles il a droit en vertu des dispositions ci-dessus, dans la mesure o\u00f9 leur valeur d\u00e9passe de plus de 10% les cr\u00e9ances \u00e0 garantir.<\/p>\n<p style=\"padding-left: 40px;\">e) si la participation de l&rsquo;acheteur est n\u00e9cessaire pour que la r\u00e9serve de propri\u00e9t\u00e9 soit effective, par exemple en cas d&rsquo;enregistrement requis par la l\u00e9gislation du pays de l&rsquo;acheteur, l&rsquo;acheteur doit proc\u00e9der \u00e0 de tels actes.<\/p>\n<p style=\"padding-left: 40px;\">f) Si l&rsquo;acheteur est en retard de paiement, le vendeur peut lui interdire de disposer de la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 en totalit\u00e9 ou, \u00e0 son choix, en partie, par exemple uniquement la vente ou la transformation, etc.<\/p>\n<p style=\"padding-left: 40px;\">g) Si les conditions objectives de l&rsquo;obligation de d\u00e9poser une demande d&rsquo;insolvabilit\u00e9 sont r\u00e9unies chez l&rsquo;acheteur, celui-ci doit &#8211; sans qu&rsquo;une demande correspondante soit n\u00e9cessaire &#8211; s&rsquo;abstenir de toute disposition sur la marchandise sous r\u00e9serve de propri\u00e9t\u00e9, de quelque nature que ce soit. L&rsquo;acheteur est tenu d&rsquo;informer imm\u00e9diatement le vendeur du stock de marchandises sous r\u00e9serve de propri\u00e9t\u00e9. Dans ce cas, le vendeur est \u00e9galement en droit de r\u00e9silier le contrat et d&rsquo;exiger la restitution de la marchandise sous r\u00e9serve de propri\u00e9t\u00e9. Si la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 a \u00e9t\u00e9 transform\u00e9e, trait\u00e9e, m\u00e9lang\u00e9e ou associ\u00e9e \u00e0 d&rsquo;autres produits, le vendeur est en droit d&rsquo;exiger sa remise \u00e0 un fiduciaire ; l&rsquo;acheteur est tenu d&rsquo;indiquer tous les copropri\u00e9taires de la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 avec leur raison sociale ou leur nom, leur adresse et leur part de copropri\u00e9t\u00e9. Il en va de m\u00eame, par analogie, pour les cr\u00e9ances qui ont \u00e9t\u00e9 c\u00e9d\u00e9es au vendeur conform\u00e9ment aux paragraphes pr\u00e9c\u00e9dents ; en outre, l&rsquo;acheteur doit transmettre spontan\u00e9ment \u00e0 l&rsquo;acheteur une copie des noms et adresses de tous les d\u00e9biteurs ainsi que des documents justifiant les cr\u00e9ances \u00e0 leur encontre.<\/p>\n<p><strong>10. caract\u00e9ristiques du produit<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) Le vendeur livre les produits dans une qualit\u00e9 qui correspond \u00e0 un premier choix, conform\u00e9ment aux directives de tri du vendeur. Ce produit peut \u00eatre soumis aux exigences commerciales habituelles en mati\u00e8re de propret\u00e9 et de beaut\u00e9 de la surface.<\/p>\n<p style=\"padding-left: 40px;\">b) En raison de la diversit\u00e9 des mat\u00e9riaux et des proc\u00e9d\u00e9s de fabrication, une s\u00e9rie peut souvent pr\u00e9senter des diff\u00e9rences de couleur en fonction des conditions d&rsquo;\u00e9clairage. Les diff\u00e9rences de dimensions, de contenu, de poids, de teintes et d&rsquo;\u00e9tat de surface dues \u00e0 la fabrication, qui restent dans le cadre des tol\u00e9rances usuelles dans le commerce, ne sont pas consid\u00e9r\u00e9es comme des d\u00e9fauts. Pour des raisons techniques d&rsquo;impression, il peut y avoir des diff\u00e9rences de couleur entre les illustrations du prospectus\/catalogue et le produit.<\/p>\n<p style=\"padding-left: 40px;\">c) Les produits de nettoyage acides et\/ou corrosifs peuvent causer des dommages s&rsquo;ils ne sont pas utilis\u00e9s correctement.<\/p>\n<p style=\"padding-left: 40px;\">d) Le vendeur se r\u00e9serve le droit d&rsquo;apporter des modifications mineures aux ex\u00e9cutions, aux couleurs et aux formes.<\/p>\n<p style=\"padding-left: 40px;\">e) Les marchandises en IIe triage ou en mini-vari\u00e9t\u00e9 ne satisfont pas aux directives de triage du vendeur et ne correspondent pas aux exigences habituelles en mati\u00e8re de design et de qualit\u00e9.<\/p>\n<p style=\"padding-left: 40px;\">f) Les ph\u00e9nom\u00e8nes d&rsquo;usure typiques (par exemple l&rsquo;abrasion du m\u00e9tal ou l&rsquo;usure due \u00e0 des produits abrasifs) ou la diminution des propri\u00e9t\u00e9s de la surface sont in\u00e9vitables selon l&rsquo;\u00e9tat de la technique et ne constituent pas un d\u00e9faut.<\/p>\n<p><strong>11. d\u00e9fauts et garantie<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) L&rsquo;acheteur doit examiner la marchandise imm\u00e9diatement apr\u00e8s la livraison, \u00e0 ses frais, et signaler par \u00e9crit au vendeur les \u00e9ventuels d\u00e9fauts visibles ainsi que les livraisons erron\u00e9es ou les quantit\u00e9s insuffisantes, sans d\u00e9lai et au plus tard apr\u00e8s un d\u00e9lai de forclusion de sept jours. Les vices cach\u00e9s doivent \u00eatre signal\u00e9s par \u00e9crit au vendeur imm\u00e9diatement apr\u00e8s leur d\u00e9couverte. Dans le cas contraire, la marchandise est consid\u00e9r\u00e9e comme accept\u00e9e.<\/p>\n<p style=\"padding-left: 40px;\">b) il n&rsquo;y a pas de d\u00e9faut en cas de livraison sup\u00e9rieure ou inf\u00e9rieure \u00e0 la quantit\u00e9 habituelle. Sont consid\u00e9r\u00e9s comme usuels dans le commerce des \u00e9carts allant jusqu&rsquo;\u00e0 5%.<\/p>\n<p style=\"padding-left: 40px;\">c) Le d\u00e9lai de garantie est d&rsquo;un an \u00e0 compter de la livraison. Les d\u00e9lais de prescription en cas de recours \u00e0 la livraison selon les articles 478 et 479 du Code civil allemand (BGB) ne sont pas affect\u00e9s par cette disposition. Les droits \u00e0 dommages et int\u00e9r\u00eats bas\u00e9s sur les d\u00e9fauts et les droits \u00e0 remboursement des d\u00e9penses en raison d&rsquo;une n\u00e9gligence grave, d&rsquo;une faute intentionnelle ou de la violation d&rsquo;obligations contractuelles essentielles (voir \u00e0 ce sujet les dispositions du point 13 \u00ab\u00a0Responsabilit\u00e9\u00a0\u00bb) ne sont pas limit\u00e9s par la pr\u00e9sente. Cela n&rsquo;affecte pas non plus les demandes de dommages et int\u00e9r\u00eats pour atteinte \u00e0 la vie, \u00e0 l&rsquo;int\u00e9grit\u00e9 physique ou \u00e0 la sant\u00e9 ou en vertu de la l\u00e9gislation sur la responsabilit\u00e9 du fait des produits.<\/p>\n<p style=\"padding-left: 40px;\">d) Les d\u00e9clarations par lesquelles l&rsquo;acheteur fait valoir d&rsquo;\u00e9ventuels droits de garantie (demande d&rsquo;ex\u00e9cution ult\u00e9rieure, d\u00e9claration de r\u00e9siliation, demande de r\u00e9duction du prix d&rsquo;achat et\/ou de dommages-int\u00e9r\u00eats) doivent \u00eatre faites par \u00e9crit pour \u00eatre valables.<\/p>\n<p style=\"padding-left: 40px; text-align: left;\"><strong>12. responsabilit\u00e9<\/strong><br \/>\na) Les demandes de dommages et int\u00e9r\u00eats de toute nature \u00e0 l&rsquo;encontre du vendeur et de ses repr\u00e9sentants l\u00e9gaux ainsi que de ses auxiliaires d&rsquo;ex\u00e9cution sont exclues, sauf en cas de faute intentionnelle ou de n\u00e9gligence grave ou de violation d&rsquo;une obligation contractuelle essentielle. Par obligation contractuelle essentielle dans ce sens, on entend toute obligation dont l&rsquo;ex\u00e9cution permet la bonne ex\u00e9cution du contrat et dont l&rsquo;acheteur peut r\u00e9guli\u00e8rement attendre le respect.<\/p>\n<p style=\"padding-left: 40px;\">b) en l&rsquo;absence de faute intentionnelle, la responsabilit\u00e9 est limit\u00e9e aux dommages typiquement pr\u00e9visibles.<\/p>\n<p style=\"padding-left: 40px;\">c) Les limitations et exclusions de responsabilit\u00e9 susmentionn\u00e9es ne s&rsquo;appliquent pas \u00e0 la responsabilit\u00e9 en vertu du droit de la responsabilit\u00e9 du fait des produits ou aux cas d&rsquo;atteinte \u00e0 la vie, \u00e0 l&rsquo;int\u00e9grit\u00e9 physique ou \u00e0 la sant\u00e9.<\/p>\n<p style=\"padding-left: 40px;\">d) Les droits du donneur d&rsquo;ordre au remboursement des d\u00e9penses selon l&rsquo;article 284 du Code civil allemand (BGB) sont exclus dans la mesure o\u00f9 un droit \u00e0 la r\u00e9paration du dommage au lieu de la prestation est exclu selon les dispositions ci-dessus.<\/p>\n<p><strong>13\u00e8me paiement<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) si aucune autre condition de paiement n&rsquo;a \u00e9t\u00e9 express\u00e9ment convenue dans le contrat, le paiement doit \u00eatre effectu\u00e9 au plus tard 10 jours apr\u00e8s la date de la facture. Pass\u00e9 ce d\u00e9lai, l&rsquo;acheteur est en d\u00e9faut. L&rsquo;int\u00e9r\u00eat moratoire s&rsquo;\u00e9l\u00e8ve \u00e0 9 points au-dessus du taux d&rsquo;int\u00e9r\u00eat de base. Le vendeur se r\u00e9serve le droit de prouver et de faire valoir un dommage plus important d\u00fb au retard. Les frais de rappel et de recouvrement ainsi que d&rsquo;autres frais \u00e9ventuels sont \u00e0 la charge de l&rsquo;acheteur.<\/p>\n<p style=\"padding-left: 40px;\">b) L&rsquo;acheteur ne dispose de droits de compensation et de r\u00e9tention que si et dans la mesure o\u00f9 ses contre-pr\u00e9tentions sont soit en rapport de r\u00e9ciprocit\u00e9 (\u00a7 320 BGB) avec les pr\u00e9tentions revendiqu\u00e9es par le vendeur, soit constat\u00e9es judiciairement par d\u00e9cision ayant acquis force de chose jug\u00e9e, soit incontest\u00e9es ou reconnues par le vendeur. En outre, l&rsquo;acheteur n&rsquo;est autoris\u00e9 \u00e0 exercer un droit de r\u00e9tention que dans la mesure o\u00f9 sa contre-pr\u00e9tention repose sur le m\u00eame rapport contractuel.<\/p>\n<p style=\"padding-left: 40px;\">c) si, apr\u00e8s la conclusion du contrat, il appara\u00eet que le droit au paiement du vendeur est menac\u00e9 par un manque de capacit\u00e9 de l&rsquo;acheteur, toutes les cr\u00e9ances ouvertes deviennent imm\u00e9diatement exigibles ; les objections et les exceptions de l&rsquo;acheteur, qui ne consistent pas \u00e0 dire qu&rsquo;une date de paiement ult\u00e9rieure a \u00e9t\u00e9 convenue, ne sont pas limit\u00e9es par ce fait.<\/p>\n<p style=\"padding-left: 40px;\">d) dans le cas o\u00f9 le vendeur est tenu de fournir une prestation pr\u00e9alable, il peut refuser de fournir la prestation qui lui incombe s&rsquo;il appara\u00eet, apr\u00e8s la conclusion du contrat, que son droit \u00e0 la contrepartie est menac\u00e9 par un manque de capacit\u00e9 de l&rsquo;acheteur. Le droit de refuser de fournir une prestation dispara\u00eet si la contrepartie est fournie ou si des garanties sont donn\u00e9es \u00e0 cet effet. Le vendeur peut fixer un d\u00e9lai raisonnable dans lequel l&rsquo;acheteur doit, \u00e0 son choix, effectuer la contre-prestation ou fournir une garantie en \u00e9change de la prestation. Si ce d\u00e9lai n&rsquo;a pas \u00e9t\u00e9 respect\u00e9, le vendeur peut r\u00e9silier le contrat.<\/p>\n<p><strong>14) Lieu d&rsquo;ex\u00e9cution, juridiction comp\u00e9tente, droit applicable<\/strong><\/p>\n<p style=\"padding-left: 40px;\">a) Le lieu d&rsquo;ex\u00e9cution pour tous les litiges r\u00e9sultant de la relation commerciale est Elmshorn. Si l&rsquo;acheteur est un commer\u00e7ant, une personne morale de droit public ou un fonds sp\u00e9cial de droit public, il est convenu que la juridiction comp\u00e9tente suppl\u00e9mentaire pour tous les litiges d\u00e9coulant du pr\u00e9sent contrat est Hambourg. La partie requ\u00e9rante a le droit de saisir \u00e0 la place le tribunal arbitral de la chambre de commerce de Hambourg. Si cela se produit, le tribunal arbitral est seul comp\u00e9tent. Le lieu d&rsquo;arbitrage est Hambourg, la langue de proc\u00e9dure est l&rsquo;allemand.<\/p>\n<p style=\"padding-left: 40px;\">b) le droit applicable est celui de la R\u00e9publique f\u00e9d\u00e9rale d&rsquo;Allemagne. Les dispositions de la Convention des Nations unies sur les contrats de vente internationale de marchandises ne s&rsquo;appliquent pas.<\/p>\n<p><strong>15. protection des donn\u00e9es<\/strong><\/p>\n<p>Le vendeur est autoris\u00e9 \u00e0 traiter et \u00e0 enregistrer les donn\u00e9es relatives \u00e0 l&rsquo;acheteur obtenues dans le cadre de la relation commerciale &#8211; m\u00eame si elles proviennent de tiers &#8211; au sens de la loi f\u00e9d\u00e9rale sur la protection des donn\u00e9es (BDSG) et \u00e0 les faire traiter et enregistrer par des tiers qu&rsquo;il a mandat\u00e9s.[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column css=\u00a0\u00bb.vc_custom_1596616112357{margin-top: 60px !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1660299905405{margin-bottom: 0px !important;}\u00a0\u00bb] CONDITIONS DE VENTE ET DE LIVRAISON DE LA SOCI\u00c9T\u00c9 MOUNT EVEREST TEA COMPANY GMBH 1) Champ d&rsquo;application des pr\u00e9sentes conditions a) Les livraisons, prestations et offres du vendeur s&rsquo;adressent exclusivement aux entrepreneurs au sens du \u00a7 14 du Code civil allemand (BGB) et sont effectu\u00e9es exclusivement sur la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3312","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conditions de vente et de livraison | Mount Everest Tea Company GmbH<\/title>\n<meta name=\"description\" content=\"Vous trouverez ici les conditions de vente et de livraison de Mount Everest Tea Company GmbH.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions de vente et de livraison | Mount Everest Tea Company GmbH\" \/>\n<meta property=\"og:description\" content=\"Vous trouverez ici les conditions de vente et de livraison de Mount Everest Tea Company GmbH.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mount-everest-tea.com\/fr\/cgv\/\" \/>\n<meta property=\"og:site_name\" content=\"Tee-Gro\u00dfhandel Mount Everest Tea\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-18T07:48:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/cgv\\\/\",\"url\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/cgv\\\/\",\"name\":\"Conditions de vente et de livraison | Mount Everest Tea Company GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-11-08T09:43:14+00:00\",\"dateModified\":\"2022-08-18T07:48:33+00:00\",\"description\":\"Vous trouverez ici les conditions de vente et de livraison de Mount Everest Tea Company GmbH.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/cgv\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/cgv\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/cgv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONDITIONS G\u00c9N\u00c9RALES DE VENTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/\",\"name\":\"Tee-Gro\u00dfhandel Mount Everest Tea\",\"description\":\"Aus Elmshorn in die ganze Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/#organization\",\"name\":\"Mount Everest Tea Company\",\"url\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mount-everest-tea.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-mount-everest-tea-company-gmbh.png\",\"contentUrl\":\"https:\\\/\\\/mount-everest-tea.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-mount-everest-tea-company-gmbh.png\",\"width\":354,\"height\":256,\"caption\":\"Mount Everest Tea Company\"},\"image\":{\"@id\":\"https:\\\/\\\/mount-everest-tea.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions de vente et de livraison | Mount Everest Tea Company GmbH","description":"Vous trouverez ici les conditions de vente et de livraison de Mount Everest Tea Company GmbH.","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Conditions de vente et de livraison | Mount Everest Tea Company GmbH","og_description":"Vous trouverez ici les conditions de vente et de livraison de Mount Everest Tea Company GmbH.","og_url":"https:\/\/mount-everest-tea.com\/fr\/cgv\/","og_site_name":"Tee-Gro\u00dfhandel Mount Everest Tea","article_modified_time":"2022-08-18T07:48:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mount-everest-tea.com\/fr\/cgv\/","url":"https:\/\/mount-everest-tea.com\/fr\/cgv\/","name":"Conditions de vente et de livraison | Mount Everest Tea Company GmbH","isPartOf":{"@id":"https:\/\/mount-everest-tea.com\/fr\/#website"},"datePublished":"2021-11-08T09:43:14+00:00","dateModified":"2022-08-18T07:48:33+00:00","description":"Vous trouverez ici les conditions de vente et de livraison de Mount Everest Tea Company GmbH.","breadcrumb":{"@id":"https:\/\/mount-everest-tea.com\/fr\/cgv\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mount-everest-tea.com\/fr\/cgv\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mount-everest-tea.com\/fr\/cgv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mount-everest-tea.com\/fr\/"},{"@type":"ListItem","position":2,"name":"CONDITIONS G\u00c9N\u00c9RALES DE VENTE"}]},{"@type":"WebSite","@id":"https:\/\/mount-everest-tea.com\/fr\/#website","url":"https:\/\/mount-everest-tea.com\/fr\/","name":"Tee-Gro\u00dfhandel Mount Everest Tea","description":"Aus Elmshorn in die ganze Welt","publisher":{"@id":"https:\/\/mount-everest-tea.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mount-everest-tea.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mount-everest-tea.com\/fr\/#organization","name":"Mount Everest Tea Company","url":"https:\/\/mount-everest-tea.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mount-everest-tea.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mount-everest-tea.com\/wp-content\/uploads\/2019\/01\/logo-mount-everest-tea-company-gmbh.png","contentUrl":"https:\/\/mount-everest-tea.com\/wp-content\/uploads\/2019\/01\/logo-mount-everest-tea-company-gmbh.png","width":354,"height":256,"caption":"Mount Everest Tea Company"},"image":{"@id":"https:\/\/mount-everest-tea.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mount-everest-tea.com\/fr\/wp-json\/wp\/v2\/pages\/3312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mount-everest-tea.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mount-everest-tea.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mount-everest-tea.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mount-everest-tea.com\/fr\/wp-json\/wp\/v2\/comments?post=3312"}],"version-history":[{"count":10,"href":"https:\/\/mount-everest-tea.com\/fr\/wp-json\/wp\/v2\/pages\/3312\/revisions"}],"predecessor-version":[{"id":3493,"href":"https:\/\/mount-everest-tea.com\/fr\/wp-json\/wp\/v2\/pages\/3312\/revisions\/3493"}],"wp:attachment":[{"href":"https:\/\/mount-everest-tea.com\/fr\/wp-json\/wp\/v2\/media?parent=3312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}